{"id":4501,"date":"2025-01-10T12:38:47","date_gmt":"2025-01-10T07:08:47","guid":{"rendered":"https:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/?page_id=4501"},"modified":"2026-02-04T12:48:51","modified_gmt":"2026-02-04T07:18:51","slug":"onlineadmission-copy","status":"publish","type":"page","link":"https:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/onlineadmission-copy\/","title":{"rendered":"UPSC OFFLINE TEST SERIES"},"content":{"rendered":"\n\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-10-at-9.12.28-PM-150x150.jpeg\" alt=\"WhatsApp Image 2025-01-10 at 9.12.28 PM\" itemprop=\"image\" height=\"150\" width=\"150\" title=\"WhatsApp Image 2025-01-10 at 9.12.28 PM\" onerror=\"this.style.display='none'\"  \/>\n\t<h1>UPSC MATHS OPTIONAL ASPIRANTS<\/h1>\n<h2><strong>Registration Open for OFFLINE LIVE TEST SERIES<\/strong><\/h2>\n\t<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-4498\"><form id=\"wpforms-form-4498\" class=\"wpforms-validate wpforms-form\" data-formid=\"4498\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/kmsform\/wp-json\/wp\/v2\/pages\/4501?wpforms_form_id=4498\" data-token=\"430abeeef4b9657db85695a924cd59f5\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-4498-field_44-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"44\"><h3 id=\"wpforms-4498-field_44\" name=\"wpforms[fields][44]\">Register your Application Form for OFFLINE Live Test Series<\/h3><\/div><div id=\"wpforms-4498-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_1\">Name of Students <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-4498-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" required><label for=\"wpforms-4498-field_1\" class=\"wpforms-field-sublabel after \">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-4498-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" required><label for=\"wpforms-4498-field_1-last\" class=\"wpforms-field-sublabel after \">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-4498-field_15-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"15\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_15\">Date of Birth <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-4498-field_15\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-large\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][15][date]\" required><a title=\"Clear Date\" data-clear class=\"wpforms-datepicker-clear\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-4498-field_8-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_8\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-4498-field_8\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][8]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-4498-field_16-container\" class=\"wpforms-field wpforms-field-select\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_16\">Gender <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-4498-field_16\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][16]\" required=\"required\"><option value=\"Male\"  selected='selected'>Male<\/option><option value=\"Female\" >Female<\/option><option value=\"Transgender\" >Transgender<\/option><\/select><\/div><div id=\"wpforms-4498-field_6-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_6\">Mobile <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-4498-field_6\" class=\"wpforms-field-large wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][6]\" placeholder=\"Enter Your Mobile Number\" required><\/div><div id=\"wpforms-4498-field_62-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"62\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_62\">Date of Submission Form<\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-4498-field_62\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][62][date]\" ><a title=\"Clear Date\" data-clear class=\"wpforms-datepicker-clear\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-4498-field_57-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"57\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_57\">Address Details <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-4498-field_57\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][57]\" required><\/textarea><\/div><div id=\"wpforms-4498-field_20-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"20\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_20\">Aspirants Aadhar No. <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" pattern=\"\\d*\" id=\"wpforms-4498-field_20\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][20]\" required><\/div><div id=\"wpforms-4498-field_66-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"66\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_66\">Select Your Offline Live Test Series (Prelims \/ MAINS) <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-4498-field_66\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-4498-field_66_1\" name=\"wpforms[fields][66][]\" value=\"UPSC MATHS OPTIONAL (PAPER 1 + PAPER 2)\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4498-field_66_1\">UPSC MATHS OPTIONAL (PAPER 1 + PAPER 2)<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-4498-field_66_2\" name=\"wpforms[fields][66][]\" value=\"UPSC Essay Optional Paper\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4498-field_66_2\">UPSC Essay Optional Paper<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-4498-field_66_3\" name=\"wpforms[fields][66][]\" value=\"CSAT Prelims Paper\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4498-field_66_3\">CSAT Prelims Paper<\/label><\/li><\/ul><\/div><div id=\"wpforms-4498-field_67-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"67\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_67\">Select Your Test Series<\/label><ul id=\"wpforms-4498-field_67\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-4498-field_67_1\" name=\"wpforms[fields][67][]\" value=\"KMS UPSC WTS (Weekly Topic wise Test Series) (1-10)\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4498-field_67_1\">KMS UPSC WTS (Weekly Topic wise Test Series) (1-10)<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-4498-field_67_2\" name=\"wpforms[fields][67][]\" value=\"KMS UPSC FTS (Full Test Series) (1-10)\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4498-field_67_2\">KMS UPSC FTS (Full Test Series) (1-10)<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-4498-field_67_3\" name=\"wpforms[fields][67][]\" value=\"KMS UPSC EPT (Essay Practice Test) (1-8) \"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4498-field_67_3\">KMS UPSC EPT (Essay Practice Test) (1-8)<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-4498-field_67_4\" name=\"wpforms[fields][67][]\" value=\"KMS UPSC CSAT PRELIMS TEST (1-7)\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4498-field_67_4\">KMS UPSC CSAT PRELIMS TEST (1-7)<\/label><\/li><\/ul><\/div><div id=\"wpforms-4498-field_39-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"39\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_39\">B.Sc.\/B.Tech from <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-4498-field_39\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][39]\" required><\/div><div id=\"wpforms-4498-field_64-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"64\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_64\">M.Sc.\/M.Tech from  <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-4498-field_64\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][64]\" required><\/div><div id=\"wpforms-4498-field_25-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"25\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_25\">KMS Students<\/label><ul id=\"wpforms-4498-field_25\"><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-4498-field_25_3\" name=\"wpforms[fields][25]\" value=\"Online Live\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4498-field_25_3\">Online Live<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-4498-field_25_4\" name=\"wpforms[fields][25]\" value=\"Offline Live\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4498-field_25_4\">Offline Live<\/label><\/li><\/ul><\/div><div id=\"wpforms-4498-field_68-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"68\"><ul id=\"wpforms-4498-field_68\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-4498-field_68_1\" name=\"wpforms[fields][68]\" value=\"Non KMS Students\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4498-field_68_1\">Non KMS Students<\/label><\/li><\/ul><\/div><div id=\"wpforms-4498-field_34-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"34\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_34\">Payment Description <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-4498-field_34\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-4498-field_34_1\" name=\"wpforms[fields][34][]\" value=\"I Paid Offline Live Test Series Amount For Next Two Attempts\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4498-field_34_1\">I Paid Offline Live Test Series Amount For Next Two Attempts<\/label><\/li><\/ul><\/div><div id=\"wpforms-4498-field_35-container\" class=\"wpforms-field wpforms-field-select\" data-field-id=\"35\"><select id=\"wpforms-4498-field_35\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][35]\" required=\"required\"><option value=\"Rs. 10,000\/- for UPSC Maths Optional Offline Live Test Series (All WTS + FTS)\" >Rs. 10,000\/- for UPSC Maths Optional Offline Live Test Series (All WTS + FTS)<\/option><option value=\"Rs. 5,000\/- for UPSC Essay Optional Live Test Series\" >Rs. 5,000\/- for UPSC Essay Optional Live Test Series<\/option><option value=\"Rs. 5,000\/- for UPSC Prilims CSAT Live Test Series\" >Rs. 5,000\/- for UPSC Prilims CSAT Live Test Series<\/option><option value=\"Offer Price Rs. 14500\/- for All UPSC Offline Live Test Series\" >Offer Price Rs. 14500\/- for All UPSC Offline Live Test Series<\/option><\/select><\/div><div id=\"wpforms-4498-field_14-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_14\">Student Photo <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"file\" id=\"wpforms-4498-field_14\" class=\"wpforms-field-required\" data-rule-extension=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,x-wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages\" data-rule-maxsize=\"1048576\" name=\"wpforms_4498_14\" accept=\".jpg,.jpeg,.jpe,.gif,.png,.bmp,.tiff,.tif,.webp,.avif,.ico,.heic,.heif,.heics,.heifs,.asf,.asx,.wmv,.wmx,.wm,.avi,.divx,.mov,.qt,.mpeg,.mpg,.mpe,.mp4,.m4v,.ogv,.webm,.mkv,.3gp,.3gpp,.3g2,.3gp2,.txt,.asc,.c,.cc,.h,.srt,.csv,.tsv,.ics,.rtx,.css,.vtt,.mp3,.m4a,.m4b,.aac,.ra,.ram,.wav,.x-wav,.ogg,.oga,.flac,.mid,.midi,.wma,.wax,.mka,.rtf,.pdf,.class,.tar,.zip,.gz,.gzip,.rar,.7z,.psd,.xcf,.doc,.pot,.pps,.ppt,.wri,.xla,.xls,.xlt,.xlw,.mpp,.docx,.docm,.dotx,.dotm,.xlsx,.xlsm,.xlsb,.xltx,.xltm,.xlam,.pptx,.pptm,.ppsx,.ppsm,.potx,.potm,.ppam,.sldx,.sldm,.onetoc,.onetoc2,.onepkg,.oxps,.xps,.odt,.odp,.ods,.odg,.odc,.odb,.odf,.wp,.wpd,.key,.numbers,.pages\" required><div class=\"wpforms-field-description\">Maximum Upload Photo Size: 1 MB<\/div><\/div><div id=\"wpforms-4498-field_47-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"47\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_47\">Payment Details Screenshot <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"file\" id=\"wpforms-4498-field_47\" class=\"wpforms-field-required\" data-rule-extension=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,x-wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages\" data-rule-maxsize=\"1048576\" name=\"wpforms_4498_47\" accept=\".jpg,.jpeg,.jpe,.gif,.png,.bmp,.tiff,.tif,.webp,.avif,.ico,.heic,.heif,.heics,.heifs,.asf,.asx,.wmv,.wmx,.wm,.avi,.divx,.mov,.qt,.mpeg,.mpg,.mpe,.mp4,.m4v,.ogv,.webm,.mkv,.3gp,.3gpp,.3g2,.3gp2,.txt,.asc,.c,.cc,.h,.srt,.csv,.tsv,.ics,.rtx,.css,.vtt,.mp3,.m4a,.m4b,.aac,.ra,.ram,.wav,.x-wav,.ogg,.oga,.flac,.mid,.midi,.wma,.wax,.mka,.rtf,.pdf,.class,.tar,.zip,.gz,.gzip,.rar,.7z,.psd,.xcf,.doc,.pot,.pps,.ppt,.wri,.xla,.xls,.xlt,.xlw,.mpp,.docx,.docm,.dotx,.dotm,.xlsx,.xlsm,.xlsb,.xltx,.xltm,.xlam,.pptx,.pptm,.ppsx,.ppsm,.potx,.potm,.ppam,.sldx,.sldm,.onetoc,.onetoc2,.onepkg,.oxps,.xps,.odt,.odp,.ods,.odg,.odc,.odb,.odf,.wp,.wpd,.key,.numbers,.pages\" required><div class=\"wpforms-field-description\">Maximum Upload Photo Size: 1 MB<\/div><\/div><div id=\"wpforms-4498-field_50-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"50\"><label class=\"wpforms-field-label\" for=\"wpforms-4498-field_50\">Terms and conditions <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-4498-field_50\" class=\"wpforms-field-required\"><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-4498-field_50_3\" name=\"wpforms[fields][50][]\" value=\"I accept the Kumar Mangalam Solutions Terms and condition\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-4498-field_50_3\">I accept the Kumar Mangalam Solutions Terms and condition<\/label><\/li><\/ul><div class=\"wpforms-field-description\"><h4> > KMS UPSC Maths Optional Students No Need to pay Test Series Fee Separately because they are paying with fees. Test Series Fees has including in course fees. Anyhow KMS Students Also have to fill Registration form for Test Series.<\/h4>\r\n<h4> > Offline live test series fees is valid for only two Attempts. After two attempts again u want to write all offline live  test series means u have to pay again and again u can get validation for two Attempts.<\/h4>\r\n<h4> > Test Series Fees is negotiable for students but that's only possible if u have good performance on our class and all previous test series respectively.<\/h4>\r\n<h4> > If Any NON KMS Students purchasing only our KMS UPSC Offline test series and afterthat on future want to join our classes then for that type students We have one offer in course fees.<\/h4>\r\n<h4> > Offer is 50% Of Test Series amount will less from KMS UPSC Course Fees.<\/h4>\r\n<h4> > Test Series Amount is NON REFUNDABLE.<\/h4><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-4498-field-hp\" class=\"wpforms-field-label\">Website<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-4498-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"4498\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-4498\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n<h3>\n\t\tYou can use both QR Code for your Comfortable\n\t<\/h3>\n\t\t<h3>Please Pay Your Fee in KMS Bank Account Details<\/h3>\t\t\n\t\t\t<hr \/>\n<h6><strong>Account Name: <\/strong>KUMAR MANGALAM SOLUTIONS<\/h6>\n<p><strong>Bank Name:<\/strong> Indian Overseas Bank<\/p>\n<p><strong>Account No.:<\/strong> 281902000000183<\/p>\n<p><strong>Account Nature:<\/strong> CURRENT ACCOUNT<\/p>\n<p><strong>IFSC:<\/strong> IOBA0002819<\/p>\n<p><strong>Branch Name:<\/strong>\u00a0Kotturpuram, Chennai<\/p>\n<strong>Branch Address:<\/strong><br \/>\nKotturpuram, Chennai-600085.\u00a0\n<strong>KMS UPI \/ GPAY NUMBER: <\/strong><br \/>\n8144550093\n\t\t\t\t<img decoding=\"async\" src=\"http:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-02-at-3.57.08-PM.jpeg\" alt=\"WhatsApp Image 2025-01-02 at 3.57.08 PM\" itemprop=\"image\" title=\"WhatsApp Image 2025-01-02 at 3.57.08 PM\" onerror=\"this.style.display='none'\"  \/>\n<h2>\n\t\tor\n\t<\/h2>\n\t\t<h3>Please Pay Your Fee in KMS Bank Account Details<\/h3>\t\t\n\t\t\t<hr \/>\n<h6><strong>Account Name: <\/strong>SUKUMAR KUMAR <\/h6>\n<p><strong>Bank Name:<\/strong> Indian Overseas Bank<\/p>\n<p><strong>Account No.:<\/strong> 281901000003321<\/p>\n<p><strong>Account Nature:<\/strong> SAVINGS ACCOUNT<\/p>\n<p><strong>IFSC:<\/strong> IOBA0002819<\/p>\n<p><strong>Branch Name:<\/strong>\u00a0Kotturpuram, Chennai<\/p>\n<strong>Branch Address:<\/strong><br \/>\nKotturpuram, Chennai-600085.\u00a0\n<strong>Sukumar Sir UPI \/  Gpay Number : <\/strong><br \/>\n8428768386\n\t\t\t\t<img decoding=\"async\" src=\"http:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/wp-content\/uploads\/2024\/12\/UPILink.jpg\" alt=\"UPILink\" itemprop=\"image\" title=\"UPILink\" onerror=\"this.style.display='none'\"  \/>\n\n","protected":false},"excerpt":{"rendered":"<p>UPSC MATHS OPTIONAL ASPIRANTS Registration Open for OFFLINE LIVE TEST SERIES You can use both QR Code for your Comfortable Please Pay Your Fee in KMS Bank Account Details Account Name: KUMAR MANGALAM SOLUTIONS Bank Name: Indian Overseas Bank Account No.: 281902000000183 Account Nature: CURRENT ACCOUNT IFSC: IOBA0002819 Branch Name:\u00a0Kotturpuram, Chennai Branch Address: Kotturpuram, Chennai-600085.\u00a0 &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/onlineadmission-copy\/\"> <span class=\"screen-reader-text\">UPSC OFFLINE TEST SERIES<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4501","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/wp-json\/wp\/v2\/pages\/4501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/wp-json\/wp\/v2\/comments?post=4501"}],"version-history":[{"count":10,"href":"https:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/wp-json\/wp\/v2\/pages\/4501\/revisions"}],"predecessor-version":[{"id":5161,"href":"https:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/wp-json\/wp\/v2\/pages\/4501\/revisions\/5161"}],"wp:attachment":[{"href":"https:\/\/onlineexam.kumarmangalamsolutions.com\/kmsform\/wp-json\/wp\/v2\/media?parent=4501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}